{"id":356,"date":"2017-05-02T20:15:06","date_gmt":"2017-05-02T20:15:06","guid":{"rendered":"http:\/\/theme.visualmodo.com\/base\/?page_id=356"},"modified":"2017-05-02T20:15:06","modified_gmt":"2017-05-02T20:15:06","slug":"count-down-timer","status":"publish","type":"page","link":"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/","title":{"rendered":"Count Down Timer"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1448211383088{margin-bottom: 0px !important;padding-top: 40px !important;padding-bottom: 70px !important;background-color: #ffffff !important;}&#8221;][vc_column]<div class=\"ult-spacer spacer-6a04c9b6c8db8\" data-id=\"6a04c9b6c8db8\" data-height=\"20\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: x-large\">Keep your users posted on what you&#8217;re upto with Count Down Timers.<\/span><\/strong><\/p>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-5668\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:100px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2017\/05\/ribbon.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5668 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Product Launch ETA<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3700\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:100px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2017\/05\/browser.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3700 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Coming Soon Page<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-4785\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:100px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2017\/05\/gear.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4785 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Website Under Maintenance<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-1916\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:100px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2017\/05\/countdown.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-1916 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Work In Progress<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-3634\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:100px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2017\/05\/scissors.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3634 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Limited Time Offer<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;]<div class=\"aio-icon-component    style_1\"><div id=\"Info-box-wrap-9876\" class=\"aio-icon-box top-icon\" style=\"\"  ><div class=\"aio-icon-top\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:100px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2017\/05\/selftimer.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-9876 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Event Announcement<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component -->[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^365|url^http:\/\/theme.visualmodo.com\/edge\/wp-content\/uploads\/sites\/2\/2017\/05\/2500&#215;1406-1_new.jpg|caption^null|alt^null|title^2500&#215;1406-1_new|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_img_attach=&#8221;fixed&#8221; bg_override=&#8221;full&#8221; font_color=&#8221;#ededed&#8221; css=&#8221;.vc_custom_1493756334085{margin-bottom: 0px !important;}&#8221; animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column]<div class=\"ult-spacer spacer-6a04c9b6c9bb5\" data-id=\"6a04c9b6c9bb5\" data-height=\"100\" data-height-mobile=\"100\" data-height-tab=\"100\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: xx-large\">WOOCOMPOSER IS COMING SOON!<\/span><\/strong><br \/>\nA set of rocking elements that will integrate WooCommerce with Visual Composer \ud83d\ude09<\/p>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a04c9b6c9bca\" data-id=\"6a04c9b6c9bca\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><style>#count-down-wrap-9712 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #efefef; } #count-down-wrap-9712 .ult_countdown-period{font-weight:normal;\tcolor: #efefef;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-9712 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-9712\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/12\/29 00:52:41\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#efefef\"   data-ultimate-target='#count-down-wrap-9712 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#efefef\" data-br-color=\"#ffffff\" data-br-style=\"solid\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"2000\" data-padd=\"20\" >2016\/12\/29 00:52:41<\/div><\/div><div class=\"ult-spacer spacer-6a04c9b6c9c67\" data-id=\"6a04c9b6c9c67\" data-height=\"5\" data-height-mobile=\"5\" data-height-tab=\"5\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Please stay tuned while we&#8217;re working hard on this.<\/span><\/p>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a04c9b6c9c79\" data-id=\"6a04c9b6c9c79\" data-height=\"100\" data-height-mobile=\"100\" data-height-tab=\"100\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; font_color=&#8221;#212121&#8243; css=&#8221;.vc_custom_1448211794140{margin-bottom: 0px !important;background-color: #ffffff !important;}&#8221;][vc_column]<div class=\"ult-spacer spacer-6a04c9b6c9c8a\" data-id=\"6a04c9b6c9c8a\" data-height=\"100\" data-height-mobile=\"100\" data-height-tab=\"100\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: xx-large\">UNLIMITED\u00a0DESIGNS!<\/span><\/strong><\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: xx-large\">Few Random Possibilities Below.<\/span><\/strong><\/p>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a04c9b6c9c9b\" data-id=\"6a04c9b6c9c9b\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Change All the Colors.<\/span><\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-6387 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #81d742; } #count-down-wrap-6387 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-6387 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-6387\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/12\/25 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#81d742\"   data-ultimate-target='#count-down-wrap-6387 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#b7b7b7\" data-br-style=\"solid\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"#f4f4f4\" data-br-radius=\"2000\" data-padd=\"20\" >2016\/12\/25 16:05:52<\/div><\/div><div class=\"ult-spacer spacer-6a04c9b6c9d09\" data-id=\"6a04c9b6c9d09\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Change All the Sizes.<\/span><\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-6662 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #81d742; } #count-down-wrap-6662 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-6662 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:20px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-6662\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/11\/25 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#81d742\"   data-ultimate-target='#count-down-wrap-6662 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:60px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#b7b7b7\" data-br-style=\"solid\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"#f4f4f4\" data-br-radius=\"2000\" data-padd=\"20\" >2016\/11\/25 16:05:52<\/div><\/div><div class=\"ult-spacer spacer-6a04c9b6c9d72\" data-id=\"6a04c9b6c9d72\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Change All the Styles.<\/span><\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-3075 .ult_countdown-amount { font-weight:normal;  font-family : ;\tcolor: #8224e3; } #count-down-wrap-3075 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-3075 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-3075\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/05\/26 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#8224e3\"   data-ultimate-target='#count-down-wrap-3075 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#eeee22\" data-br-style=\"solid\" data-br-size=\"5\"  data-tick-style=\"font-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"#dd9933\" data-br-radius=\"2000\" data-padd=\"20\" >2016\/05\/26 16:05:52<\/div><\/div><div class=\"ult-spacer spacer-6a04c9b6c9dd7\" data-id=\"6a04c9b6c9dd7\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Change All the Shapes.<\/span><\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-3854 .ult_countdown-amount { boldnitalicfont-weight:normal;font-weight:bold;font-style:italic;  font-family : ;\tcolor: #000000; } #count-down-wrap-3854 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;font-weight:bold;boldnitalic}<\/style><div \" data-ultimate-target='#count-down-wrap-3854 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-3854\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/01\/27 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-3854 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#000000\" data-br-style=\"dashed\" data-br-size=\"5\"  data-tick-style=\"boldnitalicfont-weight:normal;\"  data-tick-p-style=\"boldnitalic\"  data-bg-color=\"#f4f4f4\" data-br-radius=\"2000\" data-padd=\"20\" >2016\/01\/27 16:05:52<\/div><\/div><style>#count-down-wrap-1528 .ult_countdown-amount { boldnitalicfont-weight:normal;font-weight:bold;font-style:italic;  font-family : ;\tcolor: #000000; } #count-down-wrap-1528 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;font-weight:bold;boldnitalic}<\/style><div \" data-ultimate-target='#count-down-wrap-1528 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-1528\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/06\/10 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-1528 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#e0e0e0\" data-br-style=\"inset\" data-br-size=\"5\"  data-tick-style=\"boldnitalicfont-weight:normal;\"  data-tick-p-style=\"boldnitalic\"  data-bg-color=\"#f4f4f4\" data-br-radius=\"2000\" data-padd=\"20\" >2016\/06\/10 16:05:52<\/div><\/div><style>#count-down-wrap-1822 .ult_countdown-amount { boldnitalicfont-weight:normal;font-weight:bold;font-style:italic;  font-family : ;\tcolor: #000000; } #count-down-wrap-1822 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;font-weight:bold;boldnitalic}<\/style><div \" data-ultimate-target='#count-down-wrap-1822 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-1822\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/10\/27 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-1822 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#e0e0e0\" data-br-style=\"inset\" data-br-size=\"5\"  data-tick-style=\"boldnitalicfont-weight:normal;\"  data-tick-p-style=\"boldnitalic\"  data-bg-color=\"#f4f4f4\" data-br-radius=\"20\" data-padd=\"20\" >2016\/10\/27 16:05:52<\/div><\/div><style>#count-down-wrap-7731 .ult_countdown-amount { boldnitalicfont-weight:normal;font-weight:bold;font-style:italic;  font-family : ;\tcolor: #000000; } #count-down-wrap-7731 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;font-weight:bold;boldnitalic}<\/style><div \" data-ultimate-target='#count-down-wrap-7731 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-7731\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/05\/28 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-7731 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#e0e0e0\" data-br-style=\"double\" data-br-size=\"5\"  data-tick-style=\"boldnitalicfont-weight:normal;\"  data-tick-p-style=\"boldnitalic\"  data-bg-color=\"#f4f4f4\" data-br-radius=\"0\" data-padd=\"20\" >2016\/05\/28 16:05:52<\/div><\/div><style>#count-down-wrap-8125 .ult_countdown-amount { boldnitalicfont-weight:normal;font-weight:bold;font-style:italic;  font-family : ;\tcolor: #000000; } #count-down-wrap-8125 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;font-weight:bold;boldnitalic}<\/style><div \" data-ultimate-target='#count-down-wrap-8125 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-8125\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2017\/03\/13 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-8125 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#e0e0e0\" data-br-style=\"double\" data-br-size=\"5\"  data-tick-style=\"boldnitalicfont-weight:normal;\"  data-tick-p-style=\"boldnitalic\"  data-bg-color=\"#f4f4f4\" data-br-radius=\"0\" data-padd=\"30\" >2017\/03\/13 16:05:52<\/div><\/div><style>#count-down-wrap-7326 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-7326 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-7326 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s2\"><div id=\"count-down-wrap-7326\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/03\/16 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-7326 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#999999\" data-br-style=\"double\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"#ffffff\" data-br-radius=\"50\" data-padd=\"20\" >2016\/03\/16 16:05:52<\/div><\/div><style>#count-down-wrap-5981 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-5981 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-5981 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s2\"><div id=\"count-down-wrap-5981\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/05\/04 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-5981 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2016\/05\/04 16:05:52<\/div><\/div><style>#count-down-wrap-2844 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-2844 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-2844 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s2\"><div id=\"count-down-wrap-2844\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2017\/07\/01 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-2844 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:70px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2017\/07\/01 16:05:52<\/div><\/div><div class=\"ult-spacer spacer-6a04c9b6ca076\" data-id=\"6a04c9b6ca076\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Change the Style.<\/span><\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-8608 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-8608 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-8608 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-8608\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2021\/02\/02 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-8608 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2021\/02\/02 16:05:52<\/div><\/div><style>#count-down-wrap-6465 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-6465 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-6465 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:17px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-6465\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2019\/08\/01 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-6465 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:70px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2019\/08\/01 16:05:52<\/div><\/div><style>#count-down-wrap-1080 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #81d742; } #count-down-wrap-1080 .ult_countdown-period{font-weight:normal;\tcolor: #8224e3;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-1080 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-1080\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2023\/03\/01 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#81d742\"   data-ultimate-target='#count-down-wrap-1080 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#8224e3\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2023\/03\/01 16:05:52<\/div><\/div><style>#count-down-wrap-2139 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #999999; } #count-down-wrap-2139 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-2139 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s1\"><div id=\"count-down-wrap-2139\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2020\/03\/01 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#999999\"   data-ultimate-target='#count-down-wrap-2139 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#999999\" data-br-style=\"solid\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"50\" data-padd=\"0\" >2020\/03\/01 16:05:52<\/div><\/div><style>#count-down-wrap-1320 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #999999; } #count-down-wrap-1320 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-1320 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s1\"><div id=\"count-down-wrap-1320\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2024\/10\/01 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#999999\"   data-ultimate-target='#count-down-wrap-1320 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#999999\" data-br-style=\"solid\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"0\" data-padd=\"0\" >2024\/10\/01 16:05:52<\/div><\/div><style>#count-down-wrap-6546 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #999999; } #count-down-wrap-6546 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-6546 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s1\"><div id=\"count-down-wrap-6546\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2019\/05\/01 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#999999\"   data-ultimate-target='#count-down-wrap-6546 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#999999\" data-br-style=\"inset\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"25\" data-padd=\"0\" >2019\/05\/01 16:05:52<\/div><\/div><style>#count-down-wrap-4542 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #999999; } #count-down-wrap-4542 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-4542 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-s1\"><div id=\"count-down-wrap-4542\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2017\/08\/31 16:05:52\" data-countformat=\"WDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#999999\"   data-ultimate-target='#count-down-wrap-4542 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\" data-br-color=\"#999999\" data-br-style=\"inset\" data-br-size=\"5\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"#f7f7f7\" data-br-radius=\"25\" data-padd=\"0\" >2017\/08\/31 16:05:52<\/div><\/div><div class=\"ult-spacer spacer-6a04c9b6ca29d\" data-id=\"6a04c9b6ca29d\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Design in Any Format.<\/span><\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-3962 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-3962 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-3962 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-3962\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2017\/07\/11 16:05:52\" data-countformat=\"WDHM\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-3962 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2017\/07\/11 16:05:52<\/div><\/div><style>#count-down-wrap-3657 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-3657 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-3657 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-3657\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/11\/01 16:05:52\" data-countformat=\"YOWDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-3657 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2016\/11\/01 16:05:52<\/div><\/div><style>#count-down-wrap-6191 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-6191 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-6191 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-6191\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2017\/07\/14 16:05:52\" data-countformat=\"YODHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-6191 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2017\/07\/14 16:05:52<\/div><\/div><style>#count-down-wrap-4851 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-4851 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-4851 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-4851\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/08\/04 16:05:52\" data-countformat=\"YDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-4851 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2016\/08\/04 16:05:52<\/div><\/div><style>#count-down-wrap-8692 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-8692 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-8692 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-8692\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2017\/04\/17 16:05:52\" data-countformat=\"YHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-8692 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2017\/04\/17 16:05:52<\/div><\/div><style>#count-down-wrap-2687 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-2687 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-2687 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-2687\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2016\/11\/29 16:05:52\" data-countformat=\"DHM\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-2687 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2016\/11\/29 16:05:52<\/div><\/div><div class=\"ult-spacer spacer-6a04c9b6ca488\" data-id=\"6a04c9b6ca488\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: large\">Server Time or Local Time in Browser.<\/span><\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center\">Time remaining\u00a0depending on settings of the server.<\/p>\n<p style=\"text-align: center\">(Useful for for limited time offers where you plan to close the offer at some specific time)<\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-2545 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-2545 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-2545 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-2545\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-wptz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2018\/11\/07 16:05:52\" data-countformat=\"YOWDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-2545 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2018\/11\/07 16:05:52<\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: center\">Time remaining\u00a0depending on settings of the server.<\/p>\n<p style=\"text-align: center\">(Useful for showing time remaining for users local festival, etc.)<\/p>\n<p>[\/vc_column_text]<style>#count-down-wrap-5434 .ult_countdown-amount { boldfont-weight:normal;font-weight:bold;  font-family : ;\tcolor: #000000; } #count-down-wrap-5434 .ult_countdown-period{font-weight:normal;\tcolor: #1e73be;\tfont-family: ;}<\/style><div \" data-ultimate-target='#count-down-wrap-5434 .ult_countdown-period'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"\"}' \" class=\"ult-responsive ult_countdown   ult-cd-no-border ult-cd-s1\"><div id=\"count-down-wrap-5434\"  class=\"ult-responsive ult_countdown-div ult_countdown-dateAndTime ult-usrtz\" data-labels=\"Years,Months,Weeks,Days,Hours,Minutes,Seconds\" data-labels2=\"Year,Month,Week,Day,Hour,Minute,Second\"  data-terminal-date=\"2020\/12\/31 16:05:52\" data-countformat=\"YOWDHMS\" data-time-zone=\"0\" data-time-now=\"2026\/05\/13 18:57:58\"  data-tick-col=\"#000000\"   data-ultimate-target='#count-down-wrap-5434 .ult_countdown-amount'  data-responsive-json-new='{\"font-size\":\"desktop:45px;\",\"line-height\":\"\"}'  data-tick-p-col=\"#1e73be\"  data-tick-style=\"boldfont-weight:normal;\"  data-tick-p-style=\"\"  data-bg-color=\"\" data-br-radius=\"\" data-padd=\"0\" >2020\/12\/31 16:05:52<\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p class=\"card-text\">[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1448211383088{margin-bottom: 0px !important;padding-top: 40px !important;padding-bottom: 70px !important;background-color: #ffffff !important;}&#8221;][vc_column][vc_column_text] Keep your users posted on what you&#8217;re upto with Count Down Timers. [\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^365|url^http:\/\/theme.visualmodo.com\/edge\/wp-content\/uploads\/sites\/2\/2017\/05\/2500&#215;1406-1_new.jpg|caption^null|alt^null|title^2500&#215;1406-1_new|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_img_attach=&#8221;fixed&#8221; bg_override=&#8221;full&#8221; font_color=&#8221;#ededed&#8221; css=&#8221;.vc_custom_1493756334085{margin-bottom: 0px !important;}&#8221; animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column][vc_column_text] WOOCOMPOSER IS COMING SOON! A set of rocking elements that will [&#8230;]<\/p>\n<p class=\"m-0\"><a class=\"btn btn-outline-secondary btn-read-more\" href=\"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-356","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Count Down Timer - Petshop WordPress Theme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Count Down Timer - Petshop WordPress Theme\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1448211383088{margin-bottom: 0px !important;padding-top: 40px !important;padding-bottom: 70px !important;background-color: #ffffff !important;}&#8221;][vc_column][vc_column_text] Keep your users posted on what you&#8217;re upto with Count Down Timers. [\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^365|url^http:\/\/theme.visualmodo.com\/edge\/wp-content\/uploads\/sites\/2\/2017\/05\/2500&#215;1406-1_new.jpg|caption^null|alt^null|title^2500&#215;1406-1_new|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_img_attach=&#8221;fixed&#8221; bg_override=&#8221;full&#8221; font_color=&#8221;#ededed&#8221; css=&#8221;.vc_custom_1493756334085{margin-bottom: 0px !important;}&#8221; animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column][vc_column_text] WOOCOMPOSER IS COMING SOON! A set of rocking elements that will [...]Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/\" \/>\n<meta property=\"og:site_name\" content=\"Petshop WordPress Theme\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/count-down-timer\\\/\",\"url\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/count-down-timer\\\/\",\"name\":\"Count Down Timer - Petshop WordPress Theme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/#website\"},\"datePublished\":\"2017-05-02T20:15:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/count-down-timer\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/count-down-timer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/count-down-timer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Count Down Timer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/#website\",\"url\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/\",\"name\":\"Petshop WordPress Theme\",\"description\":\"WordPress Theme by Visualmodo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Count Down Timer - Petshop WordPress Theme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/","og_locale":"en_US","og_type":"article","og_title":"Count Down Timer - Petshop WordPress Theme","og_description":"[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1448211383088{margin-bottom: 0px !important;padding-top: 40px !important;padding-bottom: 70px !important;background-color: #ffffff !important;}&#8221;][vc_column][vc_column_text] Keep your users posted on what you&#8217;re upto with Count Down Timers. [\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^365|url^http:\/\/theme.visualmodo.com\/edge\/wp-content\/uploads\/sites\/2\/2017\/05\/2500&#215;1406-1_new.jpg|caption^null|alt^null|title^2500&#215;1406-1_new|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_img_attach=&#8221;fixed&#8221; bg_override=&#8221;full&#8221; font_color=&#8221;#ededed&#8221; css=&#8221;.vc_custom_1493756334085{margin-bottom: 0px !important;}&#8221; animation_type=&#8221;h&#8221; horizontal_animation=&#8221;left-animation&#8221; vertical_animation=&#8221;top-animation&#8221;][vc_column][vc_column_text] WOOCOMPOSER IS COMING SOON! A set of rocking elements that will [...]Read More","og_url":"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/","og_site_name":"Petshop WordPress Theme","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/","url":"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/","name":"Count Down Timer - Petshop WordPress Theme","isPartOf":{"@id":"https:\/\/theme.visualmodo.com\/petshop\/#website"},"datePublished":"2017-05-02T20:15:06+00:00","breadcrumb":{"@id":"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/theme.visualmodo.com\/petshop\/count-down-timer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/theme.visualmodo.com\/petshop\/"},{"@type":"ListItem","position":2,"name":"Count Down Timer"}]},{"@type":"WebSite","@id":"https:\/\/theme.visualmodo.com\/petshop\/#website","url":"https:\/\/theme.visualmodo.com\/petshop\/","name":"Petshop WordPress Theme","description":"WordPress Theme by Visualmodo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theme.visualmodo.com\/petshop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/pages\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":0,"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/pages\/356\/revisions"}],"wp:attachment":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/media?parent=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}