{"id":56,"date":"2013-06-07T11:07:19","date_gmt":"2013-06-07T11:07:19","guid":{"rendered":"http:\/\/demo.woothemes.com\/woocommerce\/?post_type=product&#038;p=56"},"modified":"2018-07-18T22:28:50","modified_gmt":"2018-07-18T22:28:50","slug":"roadie-dress","status":"publish","type":"product","link":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/","title":{"rendered":"Roadie Dress"},"content":{"rendered":"<p>Pellentesque habitant morbi tristique senectus et netus et malesuada fames ac turpis egestas. Vestibulum tortor quam, feugiat vitae, ultricies eget, tempor sit amet, ante. Donec eu libero sit amet quam egestas semper. Aenean ultricies mi vitae est. Mauris placerat eleifend leo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"card-text\">Pellentesque habitant morbi tristique senectus et netus et malesuada fames ac turpis egestas. Vestibulum tortor quam, feugiat vitae, ultricies eget, tempor sit amet, ante. Donec eu libero sit amet quam egestas semper. Aenean ultricies mi vitae est. Mauris placerat eleifend leo. [&#8230;]<\/p>\n<p class=\"m-0\"><a class=\"btn btn-outline-secondary btn-read-more\" href=\"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/\">Read More<\/a><\/p>\n","protected":false},"featured_media":1635,"template":"","meta":{"_links_to":"","_links_to_target":""},"product_brand":[],"product_cat":[68,121],"product_tag":[119,115,114],"class_list":{"0":"post-56","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-clothing","7":"product_cat-dogs","8":"product_tag-pets","9":"product_tag-premium","10":"product_tag-quality","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roadie Dress - Petshop WordPress Theme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roadie Dress - Petshop WordPress Theme\" \/>\n<meta property=\"og:description\" content=\"Pellentesque habitant morbi tristique senectus et netus et malesuada fames ac turpis egestas. Vestibulum tortor quam, feugiat vitae, ultricies eget, tempor sit amet, ante. Donec eu libero sit amet quam egestas semper. Aenean ultricies mi vitae est. Mauris placerat eleifend leo. [...]Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/\" \/>\n<meta property=\"og:site_name\" content=\"Petshop WordPress Theme\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-18T22:28:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2013\/06\/Roadie-Dress-Petshop-WordPress-Theme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/\",\"url\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/\",\"name\":\"Roadie Dress - Petshop WordPress Theme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/wp-content\\\/uploads\\\/sites\\\/53\\\/2013\\\/06\\\/Roadie-Dress-Petshop-WordPress-Theme.jpg\",\"datePublished\":\"2013-06-07T11:07:19+00:00\",\"dateModified\":\"2018-07-18T22:28:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/wp-content\\\/uploads\\\/sites\\\/53\\\/2013\\\/06\\\/Roadie-Dress-Petshop-WordPress-Theme.jpg\",\"contentUrl\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/wp-content\\\/uploads\\\/sites\\\/53\\\/2013\\\/06\\\/Roadie-Dress-Petshop-WordPress-Theme.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/product\\\/roadie-dress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roadie Dress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/#website\",\"url\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/\",\"name\":\"Petshop WordPress Theme\",\"description\":\"WordPress Theme by Visualmodo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/theme.visualmodo.com\\\/petshop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roadie Dress - Petshop WordPress Theme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/","og_locale":"en_US","og_type":"article","og_title":"Roadie Dress - Petshop WordPress Theme","og_description":"Pellentesque habitant morbi tristique senectus et netus et malesuada fames ac turpis egestas. Vestibulum tortor quam, feugiat vitae, ultricies eget, tempor sit amet, ante. Donec eu libero sit amet quam egestas semper. Aenean ultricies mi vitae est. Mauris placerat eleifend leo. [...]Read More","og_url":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/","og_site_name":"Petshop WordPress Theme","article_modified_time":"2018-07-18T22:28:50+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2013\/06\/Roadie-Dress-Petshop-WordPress-Theme.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/","url":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/","name":"Roadie Dress - Petshop WordPress Theme","isPartOf":{"@id":"https:\/\/theme.visualmodo.com\/petshop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/#primaryimage"},"image":{"@id":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/#primaryimage"},"thumbnailUrl":"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2013\/06\/Roadie-Dress-Petshop-WordPress-Theme.jpg","datePublished":"2013-06-07T11:07:19+00:00","dateModified":"2018-07-18T22:28:50+00:00","breadcrumb":{"@id":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/#primaryimage","url":"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2013\/06\/Roadie-Dress-Petshop-WordPress-Theme.jpg","contentUrl":"https:\/\/theme.visualmodo.com\/petshop\/wp-content\/uploads\/sites\/53\/2013\/06\/Roadie-Dress-Petshop-WordPress-Theme.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/theme.visualmodo.com\/petshop\/product\/roadie-dress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/theme.visualmodo.com\/petshop\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/theme.visualmodo.com\/petshop\/shop\/"},{"@type":"ListItem","position":3,"name":"Roadie Dress"}]},{"@type":"WebSite","@id":"https:\/\/theme.visualmodo.com\/petshop\/#website","url":"https:\/\/theme.visualmodo.com\/petshop\/","name":"Petshop WordPress Theme","description":"WordPress Theme by Visualmodo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theme.visualmodo.com\/petshop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/product\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/media\/1635"}],"wp:attachment":[{"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/media?parent=56"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/product_brand?post=56"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/product_cat?post=56"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/theme.visualmodo.com\/petshop\/wp-json\/wp\/v2\/product_tag?post=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}